{"id":321,"date":"2017-05-02T10:25:38","date_gmt":"2017-05-02T10:25:38","guid":{"rendered":"http:\/\/www.old4.commonsupport.com\/charitypro\/?page_id=321"},"modified":"2017-05-02T10:36:53","modified_gmt":"2017-05-02T10:36:53","slug":"projects-fullwidth","status":"publish","type":"page","link":"https:\/\/www.old4.commonsupport.com\/charitypro\/projects-fullwidth","title":{"rendered":"Projects Fullwidth"},"content":{"rendered":"<p><section class=\"kc-elm kc-css-264629 kc_row\"><div class=\"kc-row-container\"><div class=\"kc-wrap-columns\">\n<div class=\"kc-elm kc-css-802158 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\">\t \n\n\n<!--Gallery Section-->\n<section class=\"gallery-section fullwidth-gallery\">\n    \n    <!--Mixitup Gallery-->\n    <div class=\"mixitup-gallery\">\n        <div class=\"auto-container\">\n            <!--Filter-->\n            <div class=\"filters text-center\">\n                <ul class=\"filter-tabs filter-btns clearfix\">\n                    <li class=\"active filter\" data-role=\"button\" data-filter=\"all\">All<\/li>\n                                        <li class=\"filter\" data-role=\"button\" data-filter=\".children\">CHILDREN<\/li>\n                 \t                    <li class=\"filter\" data-role=\"button\" data-filter=\".donate\">DONATE<\/li>\n                 \t                    <li class=\"filter\" data-role=\"button\" data-filter=\".volunteer\">VOLUNTEER<\/li>\n                 \t                <\/ul>\n            <\/div>\n        <\/div>\n    \n\t\t<!--Items Container-->\n        <div class=\"filter-list clearfix\">\n            <!--Default Portfolio Item-->\n            \n\t\t\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all children donate \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/4.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/4.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/4-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/4-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/4.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all children volunteer \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/5.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/5.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/5-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/5-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/5.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all donate volunteer \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/6.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/6.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/6-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/6-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/6.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all children \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/7.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/7.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/7-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/7-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/7.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all donate \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/8.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/8.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/8-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/8-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/8.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all volunteer \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/9.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/9.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/9-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/9-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/9.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all donate \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/10.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/10.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/10-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/10-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/10.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n\t\t\t\t\n\t\t           <!--Default Portfolio Item-->\n           <div class=\"col-md-3 col-sm-6 col-xs-12 default-portfolio-item mix all children volunteer \">\n                <div class=\"inner-box\">\n                    <figure class=\"image-box\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"340\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/11.jpg\" class=\"attachment-480x340 size-480x340 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/11.jpg 480w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/11-300x213.jpg 300w, https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/11-354x250.jpg 354w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n                    <!--Overlay Box-->\n                    <div class=\"overlay-box\">\n                        <div class=\"overlay-inner\">\n                            <div class=\"content\">\n                                <a href=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/05\/11.jpg\" class=\"lightbox-image option-btn\" title=\"Image Caption Here\" data-fancybox-group=\"example-gallery\"><span class=\"fa fa-search\"><\/span><\/a>\n                                <a href=\"#\" class=\"option-btn\"><span class=\"fa fa-link\"><\/span><\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            \n  \n        <\/div>\n    <\/div>\n    <!--End Mixitup Gallery-->\n<\/section><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-585580 kc_row\"><div class=\"kc-row-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-520229 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\"><!--Sponsors Section-->\n<section class=\"sponsors-section with-border\">\n    <div class=\"auto-container\">\n        \n        <ul class=\"sponsors-carousel owl-theme owl-carousel\">\n                        <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/1.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t            <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/2.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t            <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/3.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t            <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/4.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t            <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/1.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t            <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/2.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t            <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/3.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t            <li><figure class=\"image\"><a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-content\/uploads\/2017\/04\/4.png\" alt=\"Image\"><\/a><\/figure><\/li>\n\t\t\t        <\/ul>\n        \n    <\/div>\n<\/section>\n<\/div><\/div><\/div><\/div><\/section><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-king_composer.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/pages\/321"}],"collection":[{"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":3,"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/pages\/321\/revisions"}],"predecessor-version":[{"id":325,"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/pages\/321\/revisions\/325"}],"wp:attachment":[{"href":"https:\/\/www.old4.commonsupport.com\/charitypro\/wp-json\/wp\/v2\/media?parent=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}